{"id":309,"count":2,"description":"","link":"https:\/\/fichtenfoo.net\/blog\/tag\/31-days-contest\/","name":"31 Days Contest","slug":"31-days-contest","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/fichtenfoo.net\/blog\/wp-json\/wp\/v2\/tags\/309"}],"collection":[{"href":"https:\/\/fichtenfoo.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fichtenfoo.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fichtenfoo.net\/blog\/wp-json\/wp\/v2\/posts?tags=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}